{"id":35796,"date":"2019-06-03T13:30:58","date_gmt":"2019-06-03T12:30:58","guid":{"rendered":"https:\/\/www.exchange-data.com\/veranstaltungen\/"},"modified":"2025-08-28T11:33:13","modified_gmt":"2025-08-28T10:33:13","slug":"veranstaltungen","status":"publish","type":"page","link":"https:\/\/www.exchange-data.com\/de\/veranstaltungen\/","title":{"rendered":"Veranstaltungen"},"content":{"rendered":"<div id=\"cs-content\" class=\"cs-content\"><\/div>\n","protected":false},"excerpt":{"rendered":"<p>Veranstaltungen Bevorstehende EventsEDI ist aktives Mitglied der Finanzbranche. Unser Vertriebsteam reist weltweit, um an zahlreichen Konferenzen und Fachveranstaltungen teilzunehmen. Nachfolgend finden Sie eine \u00dcbersicht unserer kommenden Events \u2013 inklusive Networking-Gelegenheiten, interaktiven Formaten<\/p>\n<a href=\"https:\/\/www.exchange-data.com\/de\/veranstaltungen\/\" class=\"more-link\">Learn More<\/a>.","protected":false},"author":23,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"template-blank-4.php","meta":{"_acf_changed":false,"inline_featured_image":false,"footnotes":""},"class_list":["post-35796","page","type-page","status-publish","hentry","no-post-thumbnail"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.5 (Yoast SEO v27.5) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Finanzdaten Ereignisse | Exchange Data International<\/title>\n<meta name=\"description\" content=\"Entdecken Sie, auf welchen Konferenzen und Events EDI weltweit vertreten ist. Nutzen Sie Networking-Chancen und lernen Sie unsere Teams vor Ort kennen.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.exchange-data.com\/de\/veranstaltungen\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Veranstaltungen | Exchange Data International\" \/>\n<meta property=\"og:description\" content=\"Entdecken Sie, auf welchen Konferenzen und Events EDI weltweit vertreten ist. Nutzen Sie Networking-Chancen und lernen Sie unsere Teams vor Ort kennen.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.exchange-data.com\/de\/veranstaltungen\/\" \/>\n<meta property=\"og:site_name\" content=\"Exchange Data International\" \/>\n<meta property=\"article:modified_time\" content=\"2025-08-28T10:33:13+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@ExchangeData\" \/>\n<meta name=\"twitter:label1\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data1\" content=\"1\u00a0Minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.exchange-data.com\\\/de\\\/veranstaltungen\\\/\",\"url\":\"https:\\\/\\\/www.exchange-data.com\\\/de\\\/veranstaltungen\\\/\",\"name\":\"Finanzdaten Ereignisse | Exchange Data International\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.exchange-data.com\\\/de\\\/#website\"},\"datePublished\":\"2019-06-03T12:30:58+00:00\",\"dateModified\":\"2025-08-28T10:33:13+00:00\",\"description\":\"Entdecken Sie, auf welchen Konferenzen und Events EDI weltweit vertreten ist. Nutzen Sie Networking-Chancen und lernen Sie unsere Teams vor Ort kennen.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.exchange-data.com\\\/de\\\/veranstaltungen\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.exchange-data.com\\\/de\\\/veranstaltungen\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.exchange-data.com\\\/de\\\/veranstaltungen\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.exchange-data.com\\\/de\\\/startseite\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Veranstaltungen\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.exchange-data.com\\\/de\\\/#website\",\"url\":\"https:\\\/\\\/www.exchange-data.com\\\/de\\\/\",\"name\":\"Exchange Data International\",\"description\":\"Doing data differently\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.exchange-data.com\\\/de\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.exchange-data.com\\\/de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.exchange-data.com\\\/de\\\/#organization\",\"name\":\"Exchange Data International\",\"url\":\"https:\\\/\\\/www.exchange-data.com\\\/de\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.exchange-data.com\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.exchange-data.com\\\/wp-content\\\/uploads\\\/2019\\\/03\\\/logo3.png\",\"contentUrl\":\"https:\\\/\\\/www.exchange-data.com\\\/wp-content\\\/uploads\\\/2019\\\/03\\\/logo3.png\",\"width\":200,\"height\":80,\"caption\":\"Exchange Data International\"},\"image\":{\"@id\":\"https:\\\/\\\/www.exchange-data.com\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/x.com\\\/ExchangeData\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/exchange-data-international\\\/?viewAsMember=true\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UC5D1OpUb22YZANRLD_Ktcgg?view_as=subscriber\"]}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Finanzdaten Ereignisse | Exchange Data International","description":"Entdecken Sie, auf welchen Konferenzen und Events EDI weltweit vertreten ist. Nutzen Sie Networking-Chancen und lernen Sie unsere Teams vor Ort kennen.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.exchange-data.com\/de\/veranstaltungen\/","og_locale":"de_DE","og_type":"article","og_title":"Veranstaltungen | Exchange Data International","og_description":"Entdecken Sie, auf welchen Konferenzen und Events EDI weltweit vertreten ist. Nutzen Sie Networking-Chancen und lernen Sie unsere Teams vor Ort kennen.","og_url":"https:\/\/www.exchange-data.com\/de\/veranstaltungen\/","og_site_name":"Exchange Data International","article_modified_time":"2025-08-28T10:33:13+00:00","twitter_card":"summary_large_image","twitter_site":"@ExchangeData","twitter_misc":{"Gesch\u00e4tzte Lesezeit":"1\u00a0Minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.exchange-data.com\/de\/veranstaltungen\/","url":"https:\/\/www.exchange-data.com\/de\/veranstaltungen\/","name":"Finanzdaten Ereignisse | Exchange Data International","isPartOf":{"@id":"https:\/\/www.exchange-data.com\/de\/#website"},"datePublished":"2019-06-03T12:30:58+00:00","dateModified":"2025-08-28T10:33:13+00:00","description":"Entdecken Sie, auf welchen Konferenzen und Events EDI weltweit vertreten ist. Nutzen Sie Networking-Chancen und lernen Sie unsere Teams vor Ort kennen.","breadcrumb":{"@id":"https:\/\/www.exchange-data.com\/de\/veranstaltungen\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.exchange-data.com\/de\/veranstaltungen\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.exchange-data.com\/de\/veranstaltungen\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.exchange-data.com\/de\/startseite\/"},{"@type":"ListItem","position":2,"name":"Veranstaltungen"}]},{"@type":"WebSite","@id":"https:\/\/www.exchange-data.com\/de\/#website","url":"https:\/\/www.exchange-data.com\/de\/","name":"Exchange Data International","description":"Doing data differently","publisher":{"@id":"https:\/\/www.exchange-data.com\/de\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.exchange-data.com\/de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/www.exchange-data.com\/de\/#organization","name":"Exchange Data International","url":"https:\/\/www.exchange-data.com\/de\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.exchange-data.com\/de\/#\/schema\/logo\/image\/","url":"https:\/\/www.exchange-data.com\/wp-content\/uploads\/2019\/03\/logo3.png","contentUrl":"https:\/\/www.exchange-data.com\/wp-content\/uploads\/2019\/03\/logo3.png","width":200,"height":80,"caption":"Exchange Data International"},"image":{"@id":"https:\/\/www.exchange-data.com\/de\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/x.com\/ExchangeData","https:\/\/www.linkedin.com\/company\/exchange-data-international\/?viewAsMember=true","https:\/\/www.youtube.com\/channel\/UC5D1OpUb22YZANRLD_Ktcgg?view_as=subscriber"]}]}},"_links":{"self":[{"href":"https:\/\/www.exchange-data.com\/de\/wp-json\/wp\/v2\/pages\/35796","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.exchange-data.com\/de\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.exchange-data.com\/de\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.exchange-data.com\/de\/wp-json\/wp\/v2\/users\/23"}],"replies":[{"embeddable":true,"href":"https:\/\/www.exchange-data.com\/de\/wp-json\/wp\/v2\/comments?post=35796"}],"version-history":[{"count":0,"href":"https:\/\/www.exchange-data.com\/de\/wp-json\/wp\/v2\/pages\/35796\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.exchange-data.com\/de\/wp-json\/wp\/v2\/media?parent=35796"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}